{"id":12356,"date":"2026-08-12T16:18:32","date_gmt":"2026-08-12T14:18:32","guid":{"rendered":"https:\/\/rcn-ong.be\/?page_id=12356"},"modified":"2026-08-13T17:43:57","modified_gmt":"2026-08-13T15:43:57","slug":"stages","status":"publish","type":"page","link":"https:\/\/rcn-ong.be\/nl\/stages\/","title":{"rendered":"Stages"},"content":{"rendered":"\n<h2 class=\"wp-block-heading\">Offre de stage<\/h2>\n\n\n\n<p><strong>Sous Convention d\u2019insertion professionnelle<br><\/strong><em>D\u00e9veloppement, Financement et Innovation<\/em><\/p>\n\n\n\n<p><strong>Dur\u00e9e du contrat<\/strong>&nbsp;: 6 mois<br><strong>Date d\u2019entr\u00e9e en fonction&nbsp;<\/strong>: d\u00e8s que possible<br><strong>Temps de travail&nbsp;<\/strong>: de pr\u00e9f\u00e9rence 100 %<br><strong>Lieu&nbsp;<\/strong>: Bruxelles<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">DESCRIPTION DE L\u2019ONG<\/h3>\n\n\n\n<p>RCN Justice &amp; D\u00e9mocratie (RCN J&amp;D) est une ONG belge. Sa mission est de promouvoir une justice inclusive, plurielle et transformative, centr\u00e9e sur les besoins et les droits des individus et des communaut\u00e9s, afin de construire des soci\u00e9t\u00e9s plus inclusives, r\u00e9silientes et pacifiques.<br>\u00c0 travers sa strat\u00e9gie 2025-2034, RCN J&amp;D structure son action autour de quatre axes prioritaires :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>le renforcement d\u2019une justice judiciaire respectueuse de l\u2019\u00c9tat de droit ;<\/li>\n\n\n\n<li>le d\u00e9veloppement de modes alternatifs de r\u00e9solution des conflits et de justices coutumi\u00e8res compatibles avec les droits humains ;<\/li>\n\n\n\n<li>la promotion d\u2019une justice transformative, attentive aux violences syst\u00e9miques, notamment bas\u00e9es sur le genre ;<\/li>\n\n\n\n<li>l\u2019accompagnement des processus de justice transitionnelle dans les soci\u00e9t\u00e9s touch\u00e9es par des violences de masse.<br>RCN J&amp;D est une organisation \u00e0 taille humaine : Le si\u00e8ge de l\u2019association, bas\u00e9 \u00e0 Bruxelles, est compos\u00e9 d\u2019une \u00e9quipe de 7 employ\u00e9.es, appuy\u00e9\u00b7es ponctuellement par des stagiaires et\/ou des b\u00e9n\u00e9voles.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">ENJEUX DU POSTE ET MISSION<\/h3>\n\n\n\n<p>RCN Justice &amp; D\u00e9mocratie finance aujourd\u2019hui l\u2019essentiel de ses activit\u00e9s gr\u00e2ce \u00e0 des bailleurs institutionnels. Afin de soutenir son d\u00e9veloppement \u00e0 long terme, de renforcer sa r\u00e9silience financi\u00e8re et de pr\u00e9server son ind\u00e9pendance, l\u2019organisation souhaite \u00e0 la fois consolider ses partenariats institutionnels et explorer de nouvelles opportunit\u00e9s de financement et de collaboration.<\/p>\n\n\n\n<p>Le\/la Stagiaire D\u00e9veloppement, Innovation et Financement contribuera directement \u00e0 cette dynamique. Aux c\u00f4t\u00e9s de la Direction et de l\u2019\u00e9quipe programmes, il\/elle participera \u00e0 l\u2019identification de nouvelles opportunit\u00e9s de financement, au d\u00e9veloppement de relations avec des fondations, entreprises et bailleurs institutionnels, aux d\u00e9marches de pr\u00e9paration et pr\u00e9sentation des dossiers de projets ainsi qu\u2019\u00e0 la r\u00e9flexion sur les futurs leviers de croissance et d\u2019impact de l\u2019organisation.<\/p>\n\n\n\n<p><br>Ce stage offre une occasion unique de d\u00e9couvrir les enjeux du d\u00e9veloppement institutionnel d\u2019une ONG internationale et de contribuer \u00e0 des projets strat\u00e9giques m\u00ealant financement, innovation, partenariats et d\u00e9veloppement organisationnel.<\/p>\n\n\n\n<p><br>Le contenu du stage pourra \u00eatre ajust\u00e9 en fonction du profil retenu. RCN J&amp;D valorise l\u2019autonomie, la cr\u00e9ativit\u00e9 et les initiatives susceptibles d\u2019enrichir l\u2019exp\u00e9rience du ou de la stagiaire tout en contribuant au d\u00e9veloppement de l\u2019organisation.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\">PRINCIPALES ACTIVIT\u00c9S<\/h3>\n\n\n\n<p>Le\/la stagiaire pourra notamment \u00eatre amen\u00e9\u00b7e \u00e0 :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>R\u00e9aliser une veille sur les opportunit\u00e9s de financement institutionnelles, philanthropiques et priv\u00e9es.<\/li>\n\n\n\n<li>Identifier et cartographier les fondations, entreprises, bailleurs institutionnels et autres partenaires potentiels.<\/li>\n\n\n\n<li>Participer \u00e0 la pr\u00e9paration de notes conceptuelles, demandes de subvention, dossiers de partenariat et pr\u00e9sentations institutionnelles.<\/li>\n\n\n\n<li>Assurer le suivi et la mise \u00e0 jour des outils de prospection et de d\u00e9veloppement<\/li>\n\n\n\n<li>Participer \u00e0 la pr\u00e9paration de rendez-vous et d\u2019\u00e9changes avec des partenaires potentiels.<\/li>\n\n\n\n<li>Contribuer aux r\u00e9flexions strat\u00e9giques relatives au d\u00e9veloppement institutionnel, aux mod\u00e8les de financement et aux partenariats.<\/li>\n\n\n\n<li>Participer \u00e0 des chantiers transversaux tels que l\u2019\u00e9laboration d\u2019une charte \u00e9thique des partenariats et financements, l\u2019analyse de bonnes pratiques ou l\u2019exploration de nouvelles formes de collaboration.<\/li>\n\n\n\n<li>Appuyer toute initiative contribuant au d\u00e9veloppement, \u00e0 l\u2019innovation et \u00e0 l\u2019impact de RCN Justice &amp; D\u00e9mocratie.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">PROFIL RECHERCH\u00c9<\/h3>\n\n\n\n<p>Ce stage s\u2019adresse \u00e0 une personne dynamique, curieuse et entreprenante, d\u00e9sireuse de mettre ses comp\u00e9tences au service des valeurs de RCN Justice &amp; D\u00e9mocratie et de contribuer au d\u00e9veloppement d\u2019une organisation engag\u00e9e en faveur de l\u2019acc\u00e8s \u00e0 la justice, de son pouvoir de transformation des soci\u00e9t\u00e9s, des droits humains, et de la construction de soci\u00e9t\u00e9s plus inclusives et pacifiques :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00c9tudiant\u00b7e en \u00e9cole de commerce ou en master (\u00e9conomie, gestion, finance, marketing, communication, droit, gestion de projet ou domaine connexe).<\/li>\n\n\n\n<li>Passionn\u00e9\u00b7e par l\u2019impact social, le d\u00e9veloppement, la philanthropie et la mobilisation de ressources.<\/li>\n\n\n\n<li>Curieux\u00b7se, proactif\u00b7ve et dot\u00e9\u00b7e d\u2019un r\u00e9el int\u00e9r\u00eat pour la recherche de financements, les partenariats strat\u00e9giques et l\u2019innovation.<\/li>\n\n\n\n<li>\u00c0 l\u2019aise dans les contacts humains et motiv\u00e9\u00b7e par le d\u00e9veloppement de r\u00e9seaux et de collaborations.<\/li>\n\n\n\n<li>Capable de mener des recherches, analyser des opportunit\u00e9s et transformer des id\u00e9es en pistes d\u2019action concr\u00e8tes.<\/li>\n\n\n\n<li>Autonome, organis\u00e9\u00b7e et force de proposition.<\/li>\n\n\n\n<li>Excellente ma\u00eetrise du fran\u00e7ais ; la connaissance de l\u2019anglais est un atout.<\/li>\n\n\n\n<li>Sensible aux enjeux du secteur associatif, de la coop\u00e9ration internationale, des droits humains et de la justice sociale.<\/li>\n<\/ul>\n\n\n\n<h3 class=\"wp-block-heading\">CE QUE NOUS OFFRONS\/CONDITIONS DU STAGE<\/h3>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Stage sous Convention d\u2019Immersion Professionnelle<\/li>\n\n\n\n<li>Dur\u00e9e de la convention : 6 mois maximum<\/li>\n\n\n\n<li>R\u00e9gime de temps de travail : plein temps (38h\/semaine)<\/li>\n\n\n\n<li>Indemnit\u00e9 de stage de 1 116.80 \u20ac bruts<\/li>\n\n\n\n<li>Assurance Accidents du travail<\/li>\n\n\n\n<li>T\u00e9l\u00e9travail : 2 jours\/semaine<\/li>\n\n\n\n<li>Encadrement structur\u00e9 avec r\u00e9unions r\u00e9guli\u00e8res de suivi et d\u2019\u00e9change<\/li>\n\n\n\n<li>Programmation de formation \u00e0 discuter en fonction du profil<\/li>\n<\/ul>\n\n\n\n<p><strong>Int\u00e9ress\u00e9(e) ?<br><\/strong>Postulez\u00a0<strong>au plus tard le 28 ao\u00fbt 2026\u00a0<\/strong>en adressant votre candidature \u00e0 l\u2019adresse\u00a0<a href=\"mailto:job@rcn-ong.be\">job@rcn-ong.be<\/a>\u00a0avec la mention \u00ab Recrutement Stage \u00bb en objet. Veuillez adresser vos questions exclusivement par email \u00e0\u00a0<a href=\"mailto:job@rcn-ong.be\">job@rcn-ong.be<\/a>.<br><br>Une lettre de motivation accompagn\u00e9e d\u2019un CV de maximum 3 pages, ainsi que les coordonn\u00e9es de 3 personnes de r\u00e9f\u00e9rence seront jointes \u00e0 la candidature.<br><br>Les candidatures seront analys\u00e9es au fur et \u00e0 mesure. RCN J&amp;D se r\u00e9serve donc la possibilit\u00e9 de cl\u00f4turer le recrutement avant la date limite fix\u00e9e.<br><br>Des informations sur les activit\u00e9s de RCN Justice &amp; D\u00e9mocratie sont accessibles sur le site de RCN J&amp;D\u00a0<a href=\"http:\/\/www.rcn-ong.be\/\" target=\"_blank\" rel=\"noreferrer noopener\">www.rcn-ong.be<\/a>.<br><br><strong>Comment la s\u00e9lection est-elle effectu\u00e9e ?<\/strong><br>Apr\u00e8s une pr\u00e9s\u00e9lection des candidatures re\u00e7ues, les candidat\u00b7es qui correspondent le mieux au profil requis seront invit\u00e9\u00b7es \u00e0 une \u00e9preuve \u00e9crite au bureau de RCN J&amp;D, suivie d\u2019un entretien oral au cours desquels leurs connaissances, leurs savoir-\u00eatre et savoir-faire seront appr\u00e9ci\u00e9es.<br><br><strong>\u00c9galit\u00e9 des chances et diversit\u00e9<br><\/strong>Notre politique du personnel est bas\u00e9e sur la diversit\u00e9 et l\u2019\u00e9galit\u00e9 des chances. Nous s\u00e9lectionnons les candidat\u00b7es sur la base de leurs qualit\u00e9s, ind\u00e9pendamment de leur \u00e2ge, de leur sexe, de leur origine, de leurs convictions, de leur handicap, de leur nationalit\u00e9, etc.<br><br><strong>Candidat\u00b7es en situation de handicap, avec difficult\u00e9s d\u2019apprentissage ou maladie<br><\/strong>Vous pouvez demander une adaptation raisonnable de la proc\u00e9dure de s\u00e9lection m\u00eame si vous ne disposez pas d\u2019une attestation valable. Il vous suffit de donner une description de votre handicap\/maladie\/difficult\u00e9 d\u2019apprentissage et d\u2019indiquer \u00e9galement quels ajustements peuvent \u00eatre faits pour vous aider. RCN J&amp;D s\u2019efforcera de les mettre \u00e0 votre disposition.<br><br><strong>Protection des donn\u00e9es<br><\/strong>Conform\u00e9ment au r\u00e8glement g\u00e9n\u00e9ral sur la protection des donn\u00e9es, RCN J&amp;D ne traitera que les donn\u00e9es personnelles qui sont n\u00e9cessaires au recrutement et \u00e0 l\u2019\u00e9valuation de l\u2019aptitude du\u00b7de la candidat\u00b7e \u00e0 occuper le poste. Celles-ci ne seront conserv\u00e9es qu\u2019aux fins de justifier la d\u00e9cision \u00e0 prendre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Offre de stage<\/p>\n<p><strong>Sous Convention d\u2019insertion professionnelle<br \/><\/strong><em>D\u00e9veloppement, Financement et Innovation<\/em><\/p>\n<p><strong>Dur\u00e9e du contrat<\/strong>&nbsp;: 6 mois<br \/><strong>Date d\u2019entr\u00e9e en fonction&nbsp;<\/strong>: d\u00e8s que possible<br \/><strong>Temps de travail&nbsp;<\/strong><\/p>\n<p><span class=\"ellipsis\">&hellip;<\/span><\/p>\n<div class=\"read-more\"><a href=\"https:\/\/rcn-ong.be\/nl\/stages\/\">Lees meer &#8250;<\/a><\/div>\n<p><!-- end of .read-more --><\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-12356","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/rcn-ong.be\/nl\/wp-json\/wp\/v2\/pages\/12356","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rcn-ong.be\/nl\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/rcn-ong.be\/nl\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/rcn-ong.be\/nl\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/rcn-ong.be\/nl\/wp-json\/wp\/v2\/comments?post=12356"}],"version-history":[{"count":3,"href":"https:\/\/rcn-ong.be\/nl\/wp-json\/wp\/v2\/pages\/12356\/revisions"}],"predecessor-version":[{"id":12374,"href":"https:\/\/rcn-ong.be\/nl\/wp-json\/wp\/v2\/pages\/12356\/revisions\/12374"}],"wp:attachment":[{"href":"https:\/\/rcn-ong.be\/nl\/wp-json\/wp\/v2\/media?parent=12356"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}